{"id":18423,"date":"2020-12-08T18:24:41","date_gmt":"2020-12-08T17:24:41","guid":{"rendered":"https:\/\/www.travel-insight.fr\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\/"},"modified":"2020-12-08T18:24:41","modified_gmt":"2020-12-08T17:24:41","slug":"paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison","status":"publish","type":"post","link":"https:\/\/www.travel-insight.fr\/es\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\/","title":{"rendered":"Paradiski se organiza para este invierno: Entrevista con Thomas Saison"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><a href=\"https:\/\/paradiski.com\/\">Paradiski<\/a> es un dominio esquiable que ofrece un terreno de juego \u00fanico e ilimitado para los amantes de la monta\u00f1a, y m\u00e1s concretamente para los esquiadores.<br \/>\nEs una instalaci\u00f3n r\u00e1pida y moderna, con remontes ultraeficaces y nieve garantizada, con m\u00e1s del 70% de las pistas a m\u00e1s de 2.000 metros de altitud.<br \/>\nTambi\u00e9n es una zona que ofrece experiencias \u00fanicas.<br \/>\nComo sabes, 2020 es un a\u00f1o complicado para las estaciones de esqu\u00ed&#8230; Por eso entrevistamos a Thomas Saison para saber m\u00e1s sobre su visi\u00f3n del sector ahora y en los pr\u00f3ximos meses.   <\/em><\/p>\n<p style=\"text-align: justify;\"><em>Una nueva entrevista del 8 de diciembre, en directo desde la estaci\u00f3n de esqu\u00ed, que actualmente no tiene remontes.<\/em><\/p>\n<hr>\n<h2 style=\"text-align: justify;\"><strong>\u00bfPuedes presentarte y presentar tu papel en Paradiski?<\/strong><\/h2>\n<p style=\"text-align: justify;\">Thomas Saison, soy Director de Marketing y Ventas de la Soci\u00e9t\u00e9 d&#8217;am\u00e9nagement de La Plagne (filial de la Compagnie des Alpes), que gestiona los remontes y el dominio esquiable de La Plagne, unido a Les Arcs por el Vanoise Express: el dominio Paradiski.<\/p>\n<p><div class=\"video-container\"><iframe style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fparadiski%2Fposts%2F10164506019035531&amp;show_text=true&amp;width=552&amp;height=652&amp;appId\" width=\"552\" height=\"652\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div><\/p>\n<h2 style=\"text-align: justify;\"><strong>\u00bfPuedes explicar qu\u00e9 incluye el dominio?  <\/strong><\/h2>\n<p style=\"text-align: justify;\">Paradiski es el segundo dominio esquiable m\u00e1s grande del mundo, compuesto por las 3 estaciones de Les Arcs, Peisey-Vallandry y La Plagne, con un total de 425 km de pistas, un aut\u00e9ntico patio de recreo para todos los aficionados a los deportes de nieve.<br \/>\nLa zona es accesible para familias y esquiadores de todos los niveles. <\/p>\n<h2 style=\"text-align: justify;\"><strong>\u00bfPuedes venir a Paradiski a pasar las fiestas sin esquiar?  <\/strong><\/h2>\n<p style=\"text-align: justify;\">A d\u00eda de hoy, seguimos a la espera de las decisiones del gobierno, pero es probable que las estaciones abran el 15 o el 19 de diciembre, ofreciendo cada una de ellas una serie de actividades como senderismo, raquetas de nieve y esqu\u00ed de traves\u00eda.<\/p>\n<p style=\"text-align: justify;\">Hay una lista de actividades que publicar\u00e1n las Oficinas de Turismo una vez que hayan hecho balance de todo lo que permanecer\u00e1 abierto de aqu\u00ed a la fecha de apertura.<br \/>\nPero deber\u00eda ser f\u00e1cil de encontrar: cines, piscinas, centros acu\u00e1ticos y las actividades al aire libre que acabo de enumerar.<br \/>\nTambi\u00e9n hay actividades ofrecidas por proveedores de servicios, que tambi\u00e9n ofrecen excursiones con raquetas de nieve y paseos en motonieve, todo ello sujeto a un posible cambio en la decisi\u00f3n del gobierno.<br \/>\nEl juicio sumario del Conseil d&#8217;Etat sobre los remontes mec\u00e1nicos se dictar\u00e1 hoy.   <\/p>\n<h2 style=\"text-align: justify;\"><strong>\u00bfTiene sentido venir a Paradiski sin los remontes?<\/strong><\/h2>\n<p style=\"text-align: justify;\">S\u00ed, \u00a1hay un mont\u00f3n de actividades!<br \/>\nAunque seguimos siendo en gran medida una zona de esqu\u00ed (el 90% de nuestros clientes vienen exclusivamente a esquiar), hay un mont\u00f3n de actividades para mantener ocupados a peque\u00f1os y mayores, y a toda la familia.<br \/>\nDebo se\u00f1alar que el horario del TGV a partir del 15 de diciembre no ha cambiado.<br \/>\nTodos los TGV que llegan a Bourg-Saint-Maurice o Aime se mantendr\u00e1n y se intensificar\u00e1n como durante un periodo normal de vacaciones.   <\/p>\n<h2 style=\"text-align: justify;\"><strong>\u00bfQui\u00e9nes son los clientes t\u00edpicos de las estaciones de esqu\u00ed?<\/strong><\/h2>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-3695 size-large\" src=\"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/12\/Post-13-Novembre-1-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/12\/Post-13-Novembre-1-1024x683.jpg 1024w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/12\/Post-13-Novembre-1-300x200.jpg 300w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/12\/Post-13-Novembre-1-768x512.jpg 768w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/12\/Post-13-Novembre-1.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p style=\"text-align: justify;\">Nuestra clientela t\u00edpica de Navidad es principalmente francesa y suele ser familiar.<br \/>\nPor supuesto, son \u00e9pocas de mucho trabajo para las familias, incluida la Nochevieja.<br \/>\nAun as\u00ed, el 90% de nuestros clientes son esquiadores y disfrutan de una estaci\u00f3n de gran altitud.<br \/>\nRecuerda que el 60% del dominio esquiable de Paradiski est\u00e1 por encima de los 2.000 metros, as\u00ed que tratamos m\u00e1s con esquiadores que con excursionistas.   <\/p>\n<h2 style=\"text-align: justify;\"><strong>\u00bfPuedes hablarnos un poco de los acontecimientos de 2021 que mantendr\u00e1n ocupado a Paradiski incluso en esta situaci\u00f3n m\u00e1s complicada de Covid?<\/strong><\/h2>\n<p style=\"text-align: justify;\">Sinceramente, hoy se han cancelado todos los programas de animaci\u00f3n de fin de a\u00f1o o incluso de principios de 2021, incluida la reciente decisi\u00f3n de prohibir los fuegos artificiales.<br \/>\nAs\u00ed pues, hoy los programas de animaci\u00f3n est\u00e1n paralizados.<br \/>\nComo est\u00e1 estrictamente prohibido reunir a m\u00e1s de 10 personas en la zona de esqu\u00ed, se han tomado todas las medidas para que no se celebren.  <\/p>\n<h2 style=\"text-align: justify;\"><strong>\u00bfEn qu\u00e9 se diferencia Paradiski de otras estaciones de esqu\u00ed?<\/strong><\/h2>\n<p style=\"text-align: justify;\">En la actualidad, Paradiski es sobre todo el segundo dominio esquiable m\u00e1s grande del mundo, con 425 km de pistas, por lo que las posibilidades de esquiar y pasear por la zona son absolutamente inmensas.<\/p>\n<p style=\"text-align: justify;\">Hay dos picos legendarios, la Aiguille Route y el Glaciar de Bellec\u00f4te: dos accidentes fabulosos a m\u00e1s de 3000 metros.<br \/>\nNo muchas estaciones de la Tarentaise tienen glaciares.<br \/>\nHoy, junto con Tignes, somos las dos \u00fanicas estaciones con un glaciar que te permite subir hasta los 3000 metros.  <\/p>\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\" data-instgrm-captioned=\"\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/B6OLAYpCmqK\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"13\">\n<div style=\"padding: 16px;\">\n<p>&nbsp;<\/p>\n<div style=\"display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display: block; height: 50px; margin: 0 auto 12px; width: 50px;\"><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\"color: #3897f0; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: 550; line-height: 18px;\">Ver esta publicaci\u00f3n en Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #f4f4f4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg);\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\"width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\"background-color: #f4f4f4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\" href=\"https:\/\/www.instagram.com\/p\/B6OLAYpCmqK\/?utm_source=ig_embed&amp;utm_campaign=loading\" target=\"_blank\" rel=\"noopener noreferrer\">Una publicaci\u00f3n compartida por Paradiski (@paradiski)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p><script async=\"\" src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n<p style=\"text-align: justify;\">En realidad, la diversidad es bastante interesante, ya que todas las estaciones parten de pueblos situados a una altitud de 1.200 metros y terminan a 3.000 metros.<br \/>\nAs\u00ed que puedes esquiar en el bosque, entre los abetos a gran altitud, o incluso esquiar fuera de pista en nuestras diversas caras norte, tanto en La Plagne como en Les Arcs. <\/p>\n<p style=\"text-align: justify;\">Y luego, sobre todo en Paradiski, se ha hecho un gran esfuerzo en los \u00faltimos a\u00f1os para crear toda una serie de zonas de diversi\u00f3n.<br \/>\nPienso en las zonas de debutantes para aprender a esquiar, las zonas de diversi\u00f3n para ni\u00f1os: la pista de diversi\u00f3n, la pista de los vaqueros, el Buffalo Park de La Plagne, y este invierno tendremos una alfombra india que ser\u00e1 una alfombra de debutantes, totalmente dedicada a los ni\u00f1os.<br \/>\nSobre el mismo tema, vaqueros e indios.<br \/>\nParadiski significa diversidad de paisajes, diversidad de esqu\u00ed y diversidad de zonas de juego.   <\/p>\n<p style=\"text-align: justify;\">La aplicaci\u00f3n Yuge es una de las aplicaciones m\u00f3viles m\u00e1s populares del mercado actual, con algo m\u00e1s de 700.000 abonados. Te permite aprovechar al m\u00e1ximo la zona de esqu\u00ed, reunirte con tus amigos, geolocalizar a tus hijos, retarte en los recorridos deportivos y tambi\u00e9n hacerte fotos en una docena de puntos selfie en los telesillas y en los distintos puntos destacables de la zona de esqu\u00ed.<\/p>\n<h2 style=\"text-align: justify;\"><strong>\u00bfQu\u00e9 ventajas tiene para los profesionales del turismo trabajar con Paradiski?<\/strong><\/h2>\n<p style=\"text-align: justify;\">As\u00ed que, para los profesionales del turismo, voy a decir que podr\u00edamos llamarlo un refugio seguro para la reventa, porque en Paradiski, en total, estamos hablando de algo m\u00e1s de 80.000 o 90.000 camas de mercado.<br \/>\nAs\u00ed que se trata de una capacidad tur\u00edstica absolutamente enorme.<br \/>\nS\u00f3lo La Plagne ya es la primera estaci\u00f3n de esqu\u00ed del mundo en cuanto a capacidad, con 57.000 camas comerciales.<br \/>\nEso la convierte en la estaci\u00f3n de esqu\u00ed m\u00e1s popular del mundo.<br \/>\nAs\u00ed que para todos los operadores y profesionales que quieran venir a La Plagne o vender La Plagne, hay una garant\u00eda de existencias absolutamente indiscutible cuando se trata de revendernos.<br \/>\nY luego est\u00e1 la garant\u00eda de nieve, porque al estar abiertos desde principios de diciembre hasta finales de abril, con un abanico de picos muy altos de 2000 a 3000 metros, es una garant\u00eda de nieve, una garant\u00eda de existencias y una garant\u00eda de precio.<br \/>\nPorque aunque hay algunos hoteles de 4 y 5 estrellas en la zona de Paradiski, en general la estaci\u00f3n est\u00e1 formada por residencias tur\u00edsticas: Pierre et Vacances en particular, MMV, Belambra y Village Club du Soleil.      <\/p>\n<p style=\"text-align: justify;\">Podr\u00eda hablar de alojamientos con una relaci\u00f3n calidad-precio relativamente buena, o al menos de buen nivel, sin caer en la trampa de los hoteles de 5 estrellas, de lujo o \u00abdemasiado premium\u00bb.<br \/>\nPor eso nos resulta tan f\u00e1cil vender Paradiski hoy. <\/p>\n<h2 style=\"text-align: justify;\"><strong>\u00bfCu\u00e1l es tu leitmotiv para la nueva temporada?<\/strong><\/h2>\n<p style=\"text-align: justify;\">La temporada 2020 finaliz\u00f3 bruscamente el 14 de marzo debido al primer confinamiento.<br \/>\nEl verano fue un indicador muy, muy bueno.<br \/>\nRealmente vimos un enorme aumento de visitantes estivales en todo Paradiski, obviamente de una clientela francesa que no pod\u00eda ir muy lejos de casa.<br \/>\nAs\u00ed que nos hemos beneficiado de este efecto sobre las vacaciones en Francia, del tiempo, que ha sido bastante suave, y de una diversificaci\u00f3n de todas las actividades en la zona de esqu\u00ed, que no es esquiable en esta \u00e9poca del a\u00f1o, pero que sigue ofreciendo actividades de ciclismo, trail running, senderismo y mapas.<br \/>\n\u00c9se fue un factor clave.    <\/p>\n<p style=\"text-align: justify;\">\u00bfC\u00f3mo afrontamos la temporada 2020-2021?<br \/>\nQuer\u00edamos empezar la temporada con fuerza, con el objetivo de arrancar con fuerza tras este par\u00f3n prematuro.<br \/>\nDe momento, va con un poco de retraso, pero estamos haciendo todo lo posible para que la temporada se ponga en marcha.<br \/>\nEn cualquier caso, estamos preparados.<br \/>\nDijimos que estar\u00edamos listos en 48 horas como m\u00e1ximo si las decisiones nos permit\u00edan abrir.<br \/>\nAlgunos de nuestros equipos, aunque est\u00e9n trabajando a jornada reducida, est\u00e1n manteniendo y preparando la zona de esqu\u00ed.<br \/>\nHay nevadas.<br \/>\nHace mucho sol y mucho fr\u00edo.<br \/>\nLa idea es estar listos lo antes posible para una apertura r\u00e1pida de toda la zona de esqu\u00ed.        <\/p>\n<h2 style=\"text-align: justify;\"><strong><img decoding=\"async\" class=\"aligncenter wp-image-3700 size-large\" src=\"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/12\/Post-11-Octobre-2-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/12\/Post-11-Octobre-2-1024x683.jpg 1024w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/12\/Post-11-Octobre-2-300x200.jpg 300w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/12\/Post-11-Octobre-2-768x512.jpg 768w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/12\/Post-11-Octobre-2-1536x1024.jpg 1536w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/12\/Post-11-Octobre-2-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/strong><\/h2>\n<h2 style=\"text-align: justify;\"><strong>\u00bfLa \u00faltima palabra?<\/strong><\/h2>\n<p style=\"text-align: justify;\">Estamos impacientes por volver a subirnos a los esqu\u00eds, y por encontrarnos con nuestros clientes habituales que, creo, tienen muchas ganas de volver a vernos, y a los que nosotros tenemos muchas ganas de volver a ver muy, muy pronto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Paradiski es un dominio esquiable que ofrece un terreno de juego \u00fanico e ilimitado para los amantes de la monta\u00f1a, y m\u00e1s concretamente para los esquiadores. Es una instalaci\u00f3n r\u00e1pida y moderna, con remontes ultraeficaces y nieve garantizada, con m\u00e1s del 70% de las pistas a m\u00e1s de 2.000 metros de altitud. Tambi\u00e9n es una&hellip; <a class=\"more-link\" href=\"https:\/\/www.travel-insight.fr\/es\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\/\">Continue reading <span class=\"screen-reader-text\">Paradiski se organiza para este invierno: Entrevista con Thomas Saison<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":13183,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[589,653],"tags":[],"class_list":["post-18423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entrevistas","category-redes-sociales","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paradiski se organiza para este invierno: Entrevista con Thomas Saison &#8211; Travel Insight<\/title>\n<meta name=\"description\" content=\"Lee las respuestas de Thomas Saison - Paradiski a nuestras preguntas en nuestro art\u00edculo para saber m\u00e1s sobre su visi\u00f3n actual y para los pr\u00f3ximos meses.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.travel-insight.fr\/es\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paradiski se organiza para este invierno: Entrevista con Thomas Saison &#8211; Travel Insight\" \/>\n<meta property=\"og:description\" content=\"Lee las respuestas de Thomas Saison - Paradiski a nuestras preguntas en nuestro art\u00edculo para saber m\u00e1s sobre su visi\u00f3n actual y para los pr\u00f3ximos meses.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.travel-insight.fr\/es\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\/\" \/>\n<meta property=\"og:site_name\" content=\"Travel Insight\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/fr-fr.facebook.com\/travelinsightfr\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-08T17:24:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/12\/ARTICLES-TS.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1185\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Stanislas Lucien\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/lustanislas?lang=fr\" \/>\n<meta name=\"twitter:site\" content=\"@travelinsightfr\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Stanislas Lucien\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\\\/\"},\"author\":{\"name\":\"Stanislas Lucien\",\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/#\\\/schema\\\/person\\\/2eb584d7c26497ac1a033e25615bb12b\"},\"headline\":\"Paradiski se organiza para este invierno: Entrevista con Thomas Saison\",\"datePublished\":\"2020-12-08T17:24:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\\\/\"},\"wordCount\":1528,\"publisher\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.travel-insight.fr\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/ARTICLES-TS.jpg\",\"articleSection\":[\"Entrevistas\",\"Redes sociales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\\\/\",\"url\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\\\/\",\"name\":\"Paradiski se organiza para este invierno: Entrevista con Thomas Saison &#8211; Travel Insight\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.travel-insight.fr\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/ARTICLES-TS.jpg\",\"datePublished\":\"2020-12-08T17:24:41+00:00\",\"description\":\"Lee las respuestas de Thomas Saison - Paradiski a nuestras preguntas en nuestro art\u00edculo para saber m\u00e1s sobre su visi\u00f3n actual y para los pr\u00f3ximos meses.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.travel-insight.fr\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/ARTICLES-TS.jpg\",\"contentUrl\":\"https:\\\/\\\/www.travel-insight.fr\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/ARTICLES-TS.jpg\",\"width\":1185,\"height\":854},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paradiski se organiza para este invierno: Entrevista con Thomas Saison\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/\",\"name\":\"Travel-Insight\",\"description\":\"Agence de communication tourisme\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/#organization\",\"name\":\"Travel-Insight\",\"url\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.travel-insight.fr\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/logo-travel-insight-identit\u00e9-visuelle-agence-influence.jpg\",\"contentUrl\":\"https:\\\/\\\/www.travel-insight.fr\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/logo-travel-insight-identit\u00e9-visuelle-agence-influence.jpg\",\"width\":800,\"height\":800,\"caption\":\"Travel-Insight\"},\"image\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/fr-fr.facebook.com\\\/travelinsightfr\\\/\",\"https:\\\/\\\/x.com\\\/travelinsightfr\",\"https:\\\/\\\/www.instagram.com\\\/travelinsightfr\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/travel-insight-strat\u00e9gie-digitale-&amp;-e-influence-du-tourisme.\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/#\\\/schema\\\/person\\\/2eb584d7c26497ac1a033e25615bb12b\",\"name\":\"Stanislas Lucien\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c991db95e2f3a51755573d538e908a82c805ab5e872d0c3c348868e5e518a5f1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c991db95e2f3a51755573d538e908a82c805ab5e872d0c3c348868e5e518a5f1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c991db95e2f3a51755573d538e908a82c805ab5e872d0c3c348868e5e518a5f1?s=96&d=mm&r=g\",\"caption\":\"Stanislas Lucien\"},\"description\":\"C\u2019est un geek, il cr\u00e9e des sites et optimise le SEO pour \u00ab s\u2019amuser \u00bb le week-end pendant qu\u2019on regarde les s\u00e9ries recommand\u00e9es par Jeanne. Mais ce passionn\u00e9 de techno et du web sait aussi communiquer et trouver le meilleur moyen pour g\u00e9n\u00e9rer du trafic ! L\u2019administratif, c\u2019est son quotidien, la communication digitale, une vocation. Il nous envoie d\u2019ailleurs un gif chaque jour, sur sa deuxi\u00e8me passion : la bonne table.\",\"sameAs\":[\"https:\\\/\\\/www.travel-insight.fr\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/stanislaslucien\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/lustanislas?lang=fr\"],\"url\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paradiski se organiza para este invierno: Entrevista con Thomas Saison &#8211; Travel Insight","description":"Lee las respuestas de Thomas Saison - Paradiski a nuestras preguntas en nuestro art\u00edculo para saber m\u00e1s sobre su visi\u00f3n actual y para los pr\u00f3ximos meses.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.travel-insight.fr\/es\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\/","og_locale":"es_ES","og_type":"article","og_title":"Paradiski se organiza para este invierno: Entrevista con Thomas Saison &#8211; Travel Insight","og_description":"Lee las respuestas de Thomas Saison - Paradiski a nuestras preguntas en nuestro art\u00edculo para saber m\u00e1s sobre su visi\u00f3n actual y para los pr\u00f3ximos meses.","og_url":"https:\/\/www.travel-insight.fr\/es\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\/","og_site_name":"Travel Insight","article_publisher":"https:\/\/fr-fr.facebook.com\/travelinsightfr\/","article_published_time":"2020-12-08T17:24:41+00:00","og_image":[{"width":1185,"height":854,"url":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/12\/ARTICLES-TS.jpg","type":"image\/jpeg"}],"author":"Stanislas Lucien","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/lustanislas?lang=fr","twitter_site":"@travelinsightfr","twitter_misc":{"Escrito por":"Stanislas Lucien","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.travel-insight.fr\/es\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\/#article","isPartOf":{"@id":"https:\/\/www.travel-insight.fr\/es\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\/"},"author":{"name":"Stanislas Lucien","@id":"https:\/\/www.travel-insight.fr\/es\/#\/schema\/person\/2eb584d7c26497ac1a033e25615bb12b"},"headline":"Paradiski se organiza para este invierno: Entrevista con Thomas Saison","datePublished":"2020-12-08T17:24:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.travel-insight.fr\/es\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\/"},"wordCount":1528,"publisher":{"@id":"https:\/\/www.travel-insight.fr\/es\/#organization"},"image":{"@id":"https:\/\/www.travel-insight.fr\/es\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\/#primaryimage"},"thumbnailUrl":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/12\/ARTICLES-TS.jpg","articleSection":["Entrevistas","Redes sociales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.travel-insight.fr\/es\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\/","url":"https:\/\/www.travel-insight.fr\/es\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\/","name":"Paradiski se organiza para este invierno: Entrevista con Thomas Saison &#8211; Travel Insight","isPartOf":{"@id":"https:\/\/www.travel-insight.fr\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.travel-insight.fr\/es\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\/#primaryimage"},"image":{"@id":"https:\/\/www.travel-insight.fr\/es\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\/#primaryimage"},"thumbnailUrl":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/12\/ARTICLES-TS.jpg","datePublished":"2020-12-08T17:24:41+00:00","description":"Lee las respuestas de Thomas Saison - Paradiski a nuestras preguntas en nuestro art\u00edculo para saber m\u00e1s sobre su visi\u00f3n actual y para los pr\u00f3ximos meses.","breadcrumb":{"@id":"https:\/\/www.travel-insight.fr\/es\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.travel-insight.fr\/es\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.travel-insight.fr\/es\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\/#primaryimage","url":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/12\/ARTICLES-TS.jpg","contentUrl":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/12\/ARTICLES-TS.jpg","width":1185,"height":854},{"@type":"BreadcrumbList","@id":"https:\/\/www.travel-insight.fr\/es\/paradiski-se-organiza-para-este-invierno-entrevista-con-thomas-saison\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.travel-insight.fr\/es\/"},{"@type":"ListItem","position":2,"name":"Paradiski se organiza para este invierno: Entrevista con Thomas Saison"}]},{"@type":"WebSite","@id":"https:\/\/www.travel-insight.fr\/es\/#website","url":"https:\/\/www.travel-insight.fr\/es\/","name":"Travel-Insight","description":"Agence de communication tourisme","publisher":{"@id":"https:\/\/www.travel-insight.fr\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.travel-insight.fr\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.travel-insight.fr\/es\/#organization","name":"Travel-Insight","url":"https:\/\/www.travel-insight.fr\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.travel-insight.fr\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/06\/logo-travel-insight-identit\u00e9-visuelle-agence-influence.jpg","contentUrl":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/06\/logo-travel-insight-identit\u00e9-visuelle-agence-influence.jpg","width":800,"height":800,"caption":"Travel-Insight"},"image":{"@id":"https:\/\/www.travel-insight.fr\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/fr-fr.facebook.com\/travelinsightfr\/","https:\/\/x.com\/travelinsightfr","https:\/\/www.instagram.com\/travelinsightfr\/","https:\/\/www.linkedin.com\/company\/travel-insight-strat\u00e9gie-digitale-&amp;-e-influence-du-tourisme."]},{"@type":"Person","@id":"https:\/\/www.travel-insight.fr\/es\/#\/schema\/person\/2eb584d7c26497ac1a033e25615bb12b","name":"Stanislas Lucien","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c991db95e2f3a51755573d538e908a82c805ab5e872d0c3c348868e5e518a5f1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c991db95e2f3a51755573d538e908a82c805ab5e872d0c3c348868e5e518a5f1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c991db95e2f3a51755573d538e908a82c805ab5e872d0c3c348868e5e518a5f1?s=96&d=mm&r=g","caption":"Stanislas Lucien"},"description":"C\u2019est un geek, il cr\u00e9e des sites et optimise le SEO pour \u00ab s\u2019amuser \u00bb le week-end pendant qu\u2019on regarde les s\u00e9ries recommand\u00e9es par Jeanne. Mais ce passionn\u00e9 de techno et du web sait aussi communiquer et trouver le meilleur moyen pour g\u00e9n\u00e9rer du trafic ! L\u2019administratif, c\u2019est son quotidien, la communication digitale, une vocation. Il nous envoie d\u2019ailleurs un gif chaque jour, sur sa deuxi\u00e8me passion : la bonne table.","sameAs":["https:\/\/www.travel-insight.fr\/","https:\/\/www.linkedin.com\/in\/stanislaslucien\/","https:\/\/x.com\/https:\/\/twitter.com\/lustanislas?lang=fr"],"url":"https:\/\/www.travel-insight.fr\/es\/author\/admin\/"}]}},"featured_image_src":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/12\/ARTICLES-TS-600x400.jpg","featured_image_src_square":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/12\/ARTICLES-TS-600x600.jpg","author_info":{"display_name":"Stanislas Lucien","author_link":"https:\/\/www.travel-insight.fr\/es\/author\/admin\/"},"jetpack_featured_media_url":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/12\/ARTICLES-TS.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.travel-insight.fr\/es\/wp-json\/wp\/v2\/posts\/18423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.travel-insight.fr\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.travel-insight.fr\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.travel-insight.fr\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.travel-insight.fr\/es\/wp-json\/wp\/v2\/comments?post=18423"}],"version-history":[{"count":0,"href":"https:\/\/www.travel-insight.fr\/es\/wp-json\/wp\/v2\/posts\/18423\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.travel-insight.fr\/es\/wp-json\/wp\/v2\/media\/13183"}],"wp:attachment":[{"href":"https:\/\/www.travel-insight.fr\/es\/wp-json\/wp\/v2\/media?parent=18423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.travel-insight.fr\/es\/wp-json\/wp\/v2\/categories?post=18423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.travel-insight.fr\/es\/wp-json\/wp\/v2\/tags?post=18423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}