{"id":18700,"date":"2022-07-11T17:19:02","date_gmt":"2022-07-11T15:19:02","guid":{"rendered":"https:\/\/www.travel-insight.fr\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\/"},"modified":"2024-09-02T16:22:28","modified_gmt":"2024-09-02T14:22:28","slug":"como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas","status":"publish","type":"post","link":"https:\/\/www.travel-insight.fr\/es\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\/","title":{"rendered":"\u00bfC\u00f3mo influyen las redes sociales en nuestra forma de viajar?\nEl nuevo turismo de masas"},"content":{"rendered":"\n<p class=\"has-text-align-justify\">No es nada nuevo, siempre nos ha gustado compartir los recuerdos de nuestros viajes: cr\u00f3nicas de viajes, \u00e1lbumes de fotos, blogs, etc.\n\u00bfQu\u00e9 impacto han tenido las redes sociales en la forma en que viajamos y compartimos nuestros viajes hoy en d\u00eda?\n\u00bfC\u00f3mo se habr\u00eda contado la Odisea de Homero en la era digital?  <\/p>\n\n<p class=\"has-text-align-justify\">Su utilidad e influencia est\u00e1n bien establecidas, y han demostrado ser esenciales para la industria tur\u00edstica en los dos \u00faltimos a\u00f1os.\nOperaciones de influencia, comunicaci\u00f3n de informaci\u00f3n, promoci\u00f3n de territorios, contenidos creados por personas influyentes&#8230; Hemos visto que <a href=\"https:\/\/www.travel-insight.fr\/lutilisation-des-reseaux-sociaux-en-france-pendant-le-confinement\/\">las redes sociales desempe\u00f1aron un papel predominante<\/a> durante la crisis de los Covid-19.\nAqu\u00ed examinamos el papel esencial que desempe\u00f1an en el turismo, sobre todo en la recuperaci\u00f3n, y c\u00f3mo, a lo largo de los a\u00f1os, se han convertido en una fuente de inspiraci\u00f3n para los viajeros.  <\/p>\n\n<p><\/p>\n\n<p class=\"has-normal-font-size\"><strong>La importancia de las redes sociales en el turismo<\/strong><\/p>\n\n<p class=\"has-text-align-justify\">Cuando preparamos nuestros viajes, cada vez nos vemos m\u00e1s influidos, consciente o inconscientemente, por factores externos, y en particular por lo que vemos en Internet o en las redes sociales.\nDesde hace unos a\u00f1os, Instagram es la red social n\u00famero uno en cuanto a inspiraci\u00f3n e influencia.\nYa sea a trav\u00e9s de hermosas fotos de lugares, compartiendo fotos o historias reales, o gracias a influencers, todos, en un momento u otro, hemos querido ir a un lugar que hemos visto en una foto o un v\u00eddeo.  <\/p>\n\n<ul class=\"wp-block-list\"><li>Seg\u00fan una encuesta de eDreams Odigeo, el 42% de los turistas reservan sus vacaciones bas\u00e1ndose en el potencial &#8220;Instagrammable&#8221; de un destino.<\/li><li>Seg\u00fan un estudio de Schofields, el 40% de los millennials utilizan Instagram para elegir los pa\u00edses a los que van a viajar.<\/li><li>Seg\u00fan un estudio de Booking, el 32% de sus usuarios prefieren establecimientos fotog\u00e9nicos para sus vacaciones.<\/li><\/ul>\n<p class=\"has-text-align-justify\">Muchos destinos se han dado cuenta de ello y se est\u00e1n posicionando cada vez m\u00e1s en las redes de moda, con el objetivo de potenciar su atractivo y llegar a un p\u00fablico aficionado a las redes sociales: los millenials.\n <a href=\"https:\/\/www.travel-insight.fr\/tiktok-va-t-il-changer-votre-communication-digitale\/\">TikTok,<\/a> con su formato de v\u00eddeo de aperitivo, est\u00e1 disfrutando de un ascenso mete\u00f3rico.\nSin embargo, pocos destinos tienen presencia en el sitio, aunque les convendr\u00eda hacerlo.  <\/p>\n\n<p class=\"has-text-align-justify\">De hecho, esta red se est\u00e1 convirtiendo en una nueva y poderosa herramienta de marketing.\nDebido a la imaginaci\u00f3n que pueden crear en los consumidores, los v\u00eddeos tienen una importancia real en las comunicaciones del sector tur\u00edstico y tienen un poder real para influir en el consumo de viajes.\nCon los confines y el cierre de fronteras, los viajeros que buscan una escapada han adquirido el h\u00e1bito de (re)experimentar sus viajes a trav\u00e9s de las redes sociales, sobre todo mediante v\u00eddeos.  <\/p>\n\n<p class=\"has-text-align-justify\">Seg\u00fan TikTok Francia, los viajes son uno de los cinco temas m\u00e1s seguidos en la aplicaci\u00f3n.\nEsta red representa un importante potencial narrativo para un destino o una marca tur\u00edstica, ya que permite a los usuarios evadirse, descubrir, inspirarse y planificar sus pr\u00f3ximos destinos. <\/p>\n\n<p class=\"has-text-align-justify\">Este tema tambi\u00e9n tiene la ventaja de estar dirigido a un p\u00fablico amplio, y su contenido puede ser producido por destinos, profesionales del sector y los propios viajeros.<\/p>\n\n<p class=\"has-text-align-justify\">Como profesional del turismo, ser activo en TikTok significa estar presente en un canal de comunicaci\u00f3n moderno y din\u00e1mico.\nTambi\u00e9n significa estar atento a las expectativas de los usuarios de la red, los millenials.\nAunque la juventud de estos usuarios puede percibirse a veces como un obst\u00e1culo, no dejan de representar a los viajeros del ma\u00f1ana.\nAdem\u00e1s, estos j\u00f3venes influyen a menudo en las decisiones de sus padres a la hora de comprar y elegir destinos.\nPor tanto, es importante identificar ahora sus necesidades y adaptarse a sus expectativas ofreci\u00e9ndoles contenidos adecuados, desplegados en un canal de comunicaci\u00f3n que les guste.    <\/p>\n\n<p class=\"has-text-align-justify\">Ante esta hiperconectividad, los destinos deben gestionar su e-reputaci\u00f3n para seguir siendo atractivos para los consumidores.\nAlgunos destinos se ponen en el candelero gracias a la foto de un influencer, en detrimento de otros, por ejemplo. <\/p>\n\n<p class=\"has-text-align-justify\">Por ello, cada vez se ponen en marcha m\u00e1s estrategias de marketing de influencers, con el \u00fanico objetivo de ser cada vez m\u00e1s visibles para aumentar el tr\u00e1fico.<\/p>\n\n<p><\/p>\n\n<p class=\"has-normal-font-size\"><strong>Turismo de masas o egoturismo<\/strong><\/p>\n\n<p class=\"has-text-align-justify\">Hemos visto que Instagram y TikTok son dos plataformas que permiten a los profesionales del turismo dirigirse a una nueva generaci\u00f3n de viajeros, observar nuevas tendencias y crear inspiraci\u00f3n entre los viajeros.<\/p>\n\n<p class=\"has-text-align-justify\">Sin embargo, tambi\u00e9n hay consecuencias menos beneficiosas para los lugares y destinos, como la masificaci\u00f3n, la destrucci\u00f3n de la naturaleza y la estandarizaci\u00f3n de la experiencia.\nParece que los viajeros ya no parten s\u00f3lo para alejarse de todo o descubrir una nueva cultura, sino que buscan la foto perfecta para mostrar a su red que estuvieron en ese lugar concreto, en ese famoso punto fotogr\u00e1fico.\nTodos quieren vivir el mismo viaje.  <\/p>\n\n<p class=\"has-text-align-justify\">Es innegable que estas redes tienen una poderosa influencia en el sector tur\u00edstico.\nDe hecho, una foto publicada que coincida con &#8220;c\u00f3digos&#8221; instagrammables puede contribuir a popularizar un destino, y su geolocalizaci\u00f3n puede desencadenar la visita de miles de turistas. <\/p>\n\n<p class=\"has-text-align-justify\">Vemos la importancia de las fotos en los viajes, a veces en detrimento de la experiencia del viajero.\nLa b\u00fasqueda de la instagrameabilidad est\u00e1 amenazando la experiencia y desarrollando la estandarizaci\u00f3n de los viajes.\nEsta estandarizaci\u00f3n de las experiencias tur\u00edsticas se hace eco de la noci\u00f3n de comunidad: al visitar un lugar famoso e imitar las fotos vistas en Instagram, los consumidores tendr\u00e1n la sensaci\u00f3n de formar parte de la comunidad de viajeros, buscando el reconocimiento de los dem\u00e1s.  <\/p>\n\n<p class=\"has-text-align-justify\">Se llama egoturismo, y se refiere a la decisi\u00f3n de viajar a un destino con el \u00fanico prop\u00f3sito de aumentar la propia popularidad en Internet.\n\u00bfEste influencer o ese famoso est\u00e1 de vacaciones en Grecia?\nYo tambi\u00e9n voy a Grecia este verano porque es un destino &#8220;de moda&#8221;.  <\/p>\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/iStock-504177928-1024x683.jpg\" alt=\"\" class=\"wp-image-6326\" srcset=\"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/iStock-504177928-1024x683.jpg 1024w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/iStock-504177928-300x200.jpg 300w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/iStock-504177928-768x512.jpg 768w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/iStock-504177928-1536x1024.jpg 1536w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/iStock-504177928-2048x1365.jpg 2048w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/iStock-504177928-600x400.jpg 600w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/iStock-504177928-1568x1045.jpg 1568w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Oia, Grecia &#8211; 5 de septiembre de 2011: Montones de turistas observando la puesta de sol desde el famoso punto de encuentro nocturno en la punta de Oia.<\/figcaption><\/figure>\n<p class=\"has-normal-font-size\"><strong>Deriva<\/strong><\/p>\n\n<p class=\"has-text-align-justify\">La sobreexposici\u00f3n de un lugar como resultado de un foco digital puede llevar muy a menudo a un exceso de frecuentaci\u00f3n, lo que puede tener una serie de efectos perjudiciales.\nPor desgracia, la mayor\u00eda de las veces estos lugares instagrameables est\u00e1n fuera de los caminos trillados o son a\u00fan poco conocidos, lo que significa que no tienen la infraestructura necesaria para acoger a tanta gente, lo que a veces puede llevar a desnaturalizar el destino.\nLa b\u00fasqueda de LA foto o el v\u00eddeo perfectos puede tener consecuencias nada desde\u00f1ables, como la frecuentaci\u00f3n excesiva y los da\u00f1os a la flora y la fauna, que a veces pueden llevar a restringir las visitas o a cerrar el lugar.  <\/p>\n\n<p class=\"has-text-align-justify\">Por eso algunos destinos no dudan en crear lugares Instagrammables con la infraestructura adecuada, para atraer a los turistas al lugar de forma deliberada y bien pensada.<\/p>\n\n<p class=\"has-text-align-justify\">Es el caso de Vietnam, por ejemplo, que en 2018 cre\u00f3 un sitio &#8220;falso&#8221; en respuesta a las demandas de los Instagramers en busca de fotos perfectas.\nEl pa\u00eds ha construido un parque de atracciones en la cima del monte Bana, con infraestructuras dignas de los mayores parques tem\u00e1ticos.\nEl \u00e9xito internacional del parque est\u00e1 estrechamente ligado al Pont d&#8217;Or, que se ha hecho famoso gracias a Instagram y a los influencers.\nEn pocos meses, este lugar totalmente desconocido se convirti\u00f3 en un fen\u00f3meno mundial, atrayendo f\u00e1cilmente a varios millones de visitantes.\nEl lugar se ha convertido en una aut\u00e9ntica f\u00e1brica de selfies, con gente que viene a fotografiar las dos manos gigantes de Buda.    <\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/iStock-1174834898-1024x684.jpg\" alt=\"\" class=\"wp-image-6327\" srcset=\"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/iStock-1174834898-1024x684.jpg 1024w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/iStock-1174834898-300x200.jpg 300w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/iStock-1174834898-768x513.jpg 768w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/iStock-1174834898-1536x1026.jpg 1536w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/iStock-1174834898-2048x1368.jpg 2048w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/iStock-1174834898-600x400.jpg 600w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/iStock-1174834898-1568x1047.jpg 1568w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Danang, Vietnam 26 de mayo.\n2019.Tourist est\u00e1n caminando en el puente de oro, Bana Hill franc\u00e9s villange la famosa plance en Danang, Vietnam. <\/figcaption><\/figure>\n<p class=\"has-text-align-justify\">Otro ejemplo es la ciudad de \u00c1msterdam, v\u00edctima de su propio \u00e9xito, que ha lanzado una campa\u00f1a de comunicaci\u00f3n titulada <a href=\"https:\/\/www.youtube.com\/playlist?list=PLioFQq4Euh3d5vMd-08V683WtFYa7dB-N\">&#8220;Holanda, la nueva Cool&#8221;<\/a> (que ha ganado varios premios) para combatir el turismo de masas en \u00c1msterdam promocionando todos los destinos del pa\u00eds.<\/p>\n\n<p class=\"has-text-align-justify\">Tambi\u00e9n estamos asistiendo a la aparici\u00f3n en todo el mundo de nuevos tipos de establecimientos culturales influidos por la b\u00fasqueda de la Instagrammabilidad, como los museos selfie en los que todo est\u00e1 dispuesto y creado para hacer bonitas fotos de Instagram.\nTomemos, por ejemplo, el Museo del Helado de San Francisco, que ofrece a los visitantes la posibilidad de hacerse fotos en entornos ajardinados como piscinas de bolas, columpios y flamencos rosas gigantes. <\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/ratio3x2_1200-1024x683.jpg\" alt=\"\" class=\"wp-image-6328\" srcset=\"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/ratio3x2_1200-1024x683.jpg 1024w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/ratio3x2_1200-300x200.jpg 300w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/ratio3x2_1200-768x512.jpg 768w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/ratio3x2_1200-600x400.jpg 600w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/ratio3x2_1200.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>\u00a9Cortes\u00eda\/Katie Gibbs<\/figcaption><\/figure>\n<p class=\"has-text-align-justify\">Este \u00e9xodo tur\u00edstico creado por Instagram y TikTok tambi\u00e9n est\u00e1 distorsionando la experiencia del viaje, ya que algunos viajeros visitan lugares con el \u00fanico objetivo de recrear una foto o un v\u00eddeo, en lugar de descubrir el destino.\nEsto ya ocurre en los lagos Joffre de Canad\u00e1, donde algunos turistas ya no experimentan la naturaleza, sino que simplemente entran y salen del parque una vez que se han hecho la foto en el famoso tronco.\nAs\u00ed es como los destinos pueden perder su encanto o su reputaci\u00f3n y convertirse en nada m\u00e1s que un lugar Instagrammable.  <\/p>\n\n<p class=\"has-text-align-justify\">Otro de los escollos, y no el menor, de la b\u00fasqueda de LA foto Instagrammable, o del lugar m\u00e1s incre\u00edble para un TikTok perfecto durante un viaje, es traspasar los l\u00edmites de lo extra\u00f1o y lo peligroso.\nDesgraciadamente, muchos viajeros asumen riesgos importantes, a veces poni\u00e9ndose ellos mismos en peligro, para conseguir la foto espectacular que se har\u00e1 viral.\nComo resultado, cada vez vemos m\u00e1s comportamientos peligrosos y asunci\u00f3n de riesgos por parte de los viajeros.\nAlgunos no dudan en desafiar la ley para hacerse fotos, o en ir a sitios de dif\u00edcil acceso sin ninguna preparaci\u00f3n f\u00edsica ni itinerario.\nDesde 2008, m\u00e1s de 379 personas han muerto en todo el mundo intentando hacerse un selfie.    <\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/iStock-1269972846-1024x683.jpg\" alt=\"\" class=\"wp-image-6330\" srcset=\"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/iStock-1269972846-1024x683.jpg 1024w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/iStock-1269972846-300x200.jpg 300w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/iStock-1269972846-768x512.jpg 768w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/iStock-1269972846-1536x1024.jpg 1536w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/iStock-1269972846-2048x1365.jpg 2048w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/iStock-1269972846-600x400.jpg 600w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/iStock-1269972846-1568x1045.jpg 1568w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Selfie subacu\u00e1tico haciendo una se\u00f1al de &#8220;hang loose\/shaka&#8221; con un tibur\u00f3n ballena nadando por detr\u00e1s.<\/figcaption><\/figure>\n<p class=\"has-text-align-justify\">Como puedes ver, las redes sociales han cambiado profundamente los h\u00e1bitos de los viajeros, tanto en lo que respecta a las fuentes de inspiraci\u00f3n como a la planificaci\u00f3n del viaje. Los internautas no dudan en recurrir a numerosas fuentes, incluidas las redes sociales, para personalizar al m\u00e1ximo su experiencia.\nPor eso es vital que los profesionales del turismo est\u00e9n presentes y activos en las redes sociales adecuadas. <\/p>\n\n<p class=\"has-text-align-justify\">Hace unos a\u00f1os, vaticin\u00e1bamos el fin del turismo de masas con la aparici\u00f3n del ecoturismo y todas las dem\u00e1s formas de viaje sostenible o solidario, pero tenemos que admitir que el turismo de masas no ha dicho su \u00faltima palabra y no deja de encontrar nuevas formas de utilizarlo, como ocurre con Instagram.\nHoy en d\u00eda, ya no viajamos por el placer de descubrir lugares, sino por el placer de mostrar a los dem\u00e1s que estuvimos all\u00ed.\nEsta deriva egoc\u00e9ntrica se ve exacerbada por la moda de las redes sociales y los selfies, y constituye el nuevo turismo de masas.  <\/p>\n\n<p>Desde hace alg\u00fan tiempo est\u00e1n surgiendo nuevas tendencias para contrarrestar estos excesos, como no mostrar la geolocalizaci\u00f3n de un lugar en las fotos para no participar en el turismo de masas.\nTomemos el ejemplo de la ONG WWF Francia, que ha creado una geolocalizaci\u00f3n ficticia &#8220;Yo protejo la Naturaleza&#8221; en 2019 para luchar contra la fiebre tur\u00edstica que amenaza los parajes naturales y su biodiversidad. <\/p>\n\n<p>Corresponde a los destinos y a la industria tur\u00edstica comunicarse adecuadamente en las redes sociales para mantener el atractivo y el significado de los viajes m\u00e1s all\u00e1 del aspecto instagrameable.<\/p>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No es nada nuevo, siempre nos ha gustado compartir los recuerdos de nuestros viajes: cr\u00f3nicas de viajes, \u00e1lbumes de fotos, blogs, etc. \u00bfQu\u00e9 impacto han tenido las redes sociales en la forma en que viajamos y compartimos nuestros viajes hoy en d\u00eda? \u00bfC\u00f3mo se habr\u00eda contado la Odisea de Homero en la era digital? Su&hellip; <a class=\"more-link\" href=\"https:\/\/www.travel-insight.fr\/es\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\/\">Continue reading <span class=\"screen-reader-text\">\u00bfC\u00f3mo influyen las redes sociales en nuestra forma de viajar?<br \/>\nEl nuevo turismo de masas<\/span><\/a><\/p>\n","protected":false},"author":381,"featured_media":14975,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[653],"tags":[],"class_list":["post-18700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-redes-sociales","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00bfC\u00f3mo influyen las redes sociales en nuestra forma de viajar? Turismo de masas<\/title>\n<meta name=\"description\" content=\"\u00bfQu\u00e9 impacto han tenido las redes sociales en nuestra forma de viajar? \u00bfC\u00f3mo se habr\u00eda contado la Odisea de Homero? Turismo de masas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.travel-insight.fr\/es\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo influyen las redes sociales en nuestra forma de viajar? El nuevo turismo de masas\" \/>\n<meta property=\"og:description\" content=\"\u00bfQu\u00e9 impacto han tenido las redes sociales en nuestra forma de viajar? \u00bfC\u00f3mo se habr\u00eda contado la Odisea de Homero? Turismo de masas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.travel-insight.fr\/es\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\/\" \/>\n<meta property=\"og:site_name\" content=\"Travel Insight\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/fr-fr.facebook.com\/travelinsightfr\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-11T15:19:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-02T14:22:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/ARTICLES-NOUVEAU-SITE-copie-2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chlo\u00e9 Pieplu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@travelinsightfr\" \/>\n<meta name=\"twitter:site\" content=\"@travelinsightfr\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chlo\u00e9 Pieplu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\\\/\"},\"author\":{\"name\":\"Chlo\u00e9 Pieplu\",\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/#\\\/schema\\\/person\\\/45a2a880e6f52f3290a56c89eea903e3\"},\"headline\":\"\u00bfC\u00f3mo influyen las redes sociales en nuestra forma de viajar? El nuevo turismo de masas\",\"datePublished\":\"2022-07-11T15:19:02+00:00\",\"dateModified\":\"2024-09-02T14:22:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\\\/\"},\"wordCount\":2028,\"publisher\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.travel-insight.fr\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/ARTICLES-NOUVEAU-SITE-copie-2-1.jpg\",\"articleSection\":[\"Redes sociales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\\\/\",\"url\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\\\/\",\"name\":\"\u00bfC\u00f3mo influyen las redes sociales en nuestra forma de viajar? Turismo de masas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.travel-insight.fr\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/ARTICLES-NOUVEAU-SITE-copie-2-1.jpg\",\"datePublished\":\"2022-07-11T15:19:02+00:00\",\"dateModified\":\"2024-09-02T14:22:28+00:00\",\"description\":\"\u00bfQu\u00e9 impacto han tenido las redes sociales en nuestra forma de viajar? \u00bfC\u00f3mo se habr\u00eda contado la Odisea de Homero? Turismo de masas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.travel-insight.fr\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/ARTICLES-NOUVEAU-SITE-copie-2-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.travel-insight.fr\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/ARTICLES-NOUVEAU-SITE-copie-2-1.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfC\u00f3mo influyen las redes sociales en nuestra forma de viajar? El nuevo turismo de masas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/\",\"name\":\"Travel-Insight\",\"description\":\"Agence de communication tourisme\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/#organization\",\"name\":\"Travel-Insight\",\"url\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.travel-insight.fr\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/logo-travel-insight-identit\u00e9-visuelle-agence-influence.jpg\",\"contentUrl\":\"https:\\\/\\\/www.travel-insight.fr\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/logo-travel-insight-identit\u00e9-visuelle-agence-influence.jpg\",\"width\":800,\"height\":800,\"caption\":\"Travel-Insight\"},\"image\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/fr-fr.facebook.com\\\/travelinsightfr\\\/\",\"https:\\\/\\\/x.com\\\/travelinsightfr\",\"https:\\\/\\\/www.instagram.com\\\/travelinsightfr\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/travel-insight-strat\u00e9gie-digitale-&amp;-e-influence-du-tourisme.\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/#\\\/schema\\\/person\\\/45a2a880e6f52f3290a56c89eea903e3\",\"name\":\"Chlo\u00e9 Pieplu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0707da4786843d8f3a8f00eaec4952dae32fbbb92f298d669f5a714855cec58?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0707da4786843d8f3a8f00eaec4952dae32fbbb92f298d669f5a714855cec58?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0707da4786843d8f3a8f00eaec4952dae32fbbb92f298d669f5a714855cec58?s=96&d=mm&r=g\",\"caption\":\"Chlo\u00e9 Pieplu\"},\"description\":\"Si elle n\u2019avait pas \u00e9t\u00e9 \u00e0 l\u2019agence, elle serait sans doute blogueuse sur une plage des Bahamas. On a eu de la chance, notre Mom favorite a pr\u00e9f\u00e9r\u00e9 la vie de bureau pour animer les r\u00e9seaux de nos clients. Et elle fait d\u2019excellents cookies.\",\"sameAs\":[\"https:\\\/\\\/www.travel-insight.fr\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/chlo-alfieri-2148b55b\\\/\"],\"url\":\"https:\\\/\\\/www.travel-insight.fr\\\/es\\\/author\\\/chloe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo influyen las redes sociales en nuestra forma de viajar? Turismo de masas","description":"\u00bfQu\u00e9 impacto han tenido las redes sociales en nuestra forma de viajar? \u00bfC\u00f3mo se habr\u00eda contado la Odisea de Homero? Turismo de masas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.travel-insight.fr\/es\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfC\u00f3mo influyen las redes sociales en nuestra forma de viajar? El nuevo turismo de masas","og_description":"\u00bfQu\u00e9 impacto han tenido las redes sociales en nuestra forma de viajar? \u00bfC\u00f3mo se habr\u00eda contado la Odisea de Homero? Turismo de masas","og_url":"https:\/\/www.travel-insight.fr\/es\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\/","og_site_name":"Travel Insight","article_publisher":"https:\/\/fr-fr.facebook.com\/travelinsightfr\/","article_published_time":"2022-07-11T15:19:02+00:00","article_modified_time":"2024-09-02T14:22:28+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/ARTICLES-NOUVEAU-SITE-copie-2-1.jpg","type":"image\/jpeg"}],"author":"Chlo\u00e9 Pieplu","twitter_card":"summary_large_image","twitter_creator":"@travelinsightfr","twitter_site":"@travelinsightfr","twitter_misc":{"Escrito por":"Chlo\u00e9 Pieplu","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.travel-insight.fr\/es\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\/#article","isPartOf":{"@id":"https:\/\/www.travel-insight.fr\/es\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\/"},"author":{"name":"Chlo\u00e9 Pieplu","@id":"https:\/\/www.travel-insight.fr\/es\/#\/schema\/person\/45a2a880e6f52f3290a56c89eea903e3"},"headline":"\u00bfC\u00f3mo influyen las redes sociales en nuestra forma de viajar? El nuevo turismo de masas","datePublished":"2022-07-11T15:19:02+00:00","dateModified":"2024-09-02T14:22:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.travel-insight.fr\/es\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\/"},"wordCount":2028,"publisher":{"@id":"https:\/\/www.travel-insight.fr\/es\/#organization"},"image":{"@id":"https:\/\/www.travel-insight.fr\/es\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/ARTICLES-NOUVEAU-SITE-copie-2-1.jpg","articleSection":["Redes sociales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.travel-insight.fr\/es\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\/","url":"https:\/\/www.travel-insight.fr\/es\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\/","name":"\u00bfC\u00f3mo influyen las redes sociales en nuestra forma de viajar? Turismo de masas","isPartOf":{"@id":"https:\/\/www.travel-insight.fr\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.travel-insight.fr\/es\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\/#primaryimage"},"image":{"@id":"https:\/\/www.travel-insight.fr\/es\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/ARTICLES-NOUVEAU-SITE-copie-2-1.jpg","datePublished":"2022-07-11T15:19:02+00:00","dateModified":"2024-09-02T14:22:28+00:00","description":"\u00bfQu\u00e9 impacto han tenido las redes sociales en nuestra forma de viajar? \u00bfC\u00f3mo se habr\u00eda contado la Odisea de Homero? Turismo de masas","breadcrumb":{"@id":"https:\/\/www.travel-insight.fr\/es\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.travel-insight.fr\/es\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.travel-insight.fr\/es\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\/#primaryimage","url":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/ARTICLES-NOUVEAU-SITE-copie-2-1.jpg","contentUrl":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/ARTICLES-NOUVEAU-SITE-copie-2-1.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/www.travel-insight.fr\/es\/como-influyen-las-redes-sociales-en-nuestra-forma-de-viajarel-nuevo-turismo-de-masas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.travel-insight.fr\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfC\u00f3mo influyen las redes sociales en nuestra forma de viajar? El nuevo turismo de masas"}]},{"@type":"WebSite","@id":"https:\/\/www.travel-insight.fr\/es\/#website","url":"https:\/\/www.travel-insight.fr\/es\/","name":"Travel-Insight","description":"Agence de communication tourisme","publisher":{"@id":"https:\/\/www.travel-insight.fr\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.travel-insight.fr\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.travel-insight.fr\/es\/#organization","name":"Travel-Insight","url":"https:\/\/www.travel-insight.fr\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.travel-insight.fr\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/06\/logo-travel-insight-identit\u00e9-visuelle-agence-influence.jpg","contentUrl":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/06\/logo-travel-insight-identit\u00e9-visuelle-agence-influence.jpg","width":800,"height":800,"caption":"Travel-Insight"},"image":{"@id":"https:\/\/www.travel-insight.fr\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/fr-fr.facebook.com\/travelinsightfr\/","https:\/\/x.com\/travelinsightfr","https:\/\/www.instagram.com\/travelinsightfr\/","https:\/\/www.linkedin.com\/company\/travel-insight-strat\u00e9gie-digitale-&amp;-e-influence-du-tourisme."]},{"@type":"Person","@id":"https:\/\/www.travel-insight.fr\/es\/#\/schema\/person\/45a2a880e6f52f3290a56c89eea903e3","name":"Chlo\u00e9 Pieplu","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f0707da4786843d8f3a8f00eaec4952dae32fbbb92f298d669f5a714855cec58?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0707da4786843d8f3a8f00eaec4952dae32fbbb92f298d669f5a714855cec58?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0707da4786843d8f3a8f00eaec4952dae32fbbb92f298d669f5a714855cec58?s=96&d=mm&r=g","caption":"Chlo\u00e9 Pieplu"},"description":"Si elle n\u2019avait pas \u00e9t\u00e9 \u00e0 l\u2019agence, elle serait sans doute blogueuse sur une plage des Bahamas. On a eu de la chance, notre Mom favorite a pr\u00e9f\u00e9r\u00e9 la vie de bureau pour animer les r\u00e9seaux de nos clients. Et elle fait d\u2019excellents cookies.","sameAs":["https:\/\/www.travel-insight.fr\/","https:\/\/www.linkedin.com\/in\/chlo-alfieri-2148b55b\/"],"url":"https:\/\/www.travel-insight.fr\/es\/author\/chloe\/"}]}},"featured_image_src":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/ARTICLES-NOUVEAU-SITE-copie-2-1-600x400.jpg","featured_image_src_square":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/ARTICLES-NOUVEAU-SITE-copie-2-1-600x600.jpg","author_info":{"display_name":"Chlo\u00e9 Pieplu","author_link":"https:\/\/www.travel-insight.fr\/es\/author\/chloe\/"},"jetpack_featured_media_url":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2022\/07\/ARTICLES-NOUVEAU-SITE-copie-2-1.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.travel-insight.fr\/es\/wp-json\/wp\/v2\/posts\/18700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.travel-insight.fr\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.travel-insight.fr\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.travel-insight.fr\/es\/wp-json\/wp\/v2\/users\/381"}],"replies":[{"embeddable":true,"href":"https:\/\/www.travel-insight.fr\/es\/wp-json\/wp\/v2\/comments?post=18700"}],"version-history":[{"count":1,"href":"https:\/\/www.travel-insight.fr\/es\/wp-json\/wp\/v2\/posts\/18700\/revisions"}],"predecessor-version":[{"id":18702,"href":"https:\/\/www.travel-insight.fr\/es\/wp-json\/wp\/v2\/posts\/18700\/revisions\/18702"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.travel-insight.fr\/es\/wp-json\/wp\/v2\/media\/14975"}],"wp:attachment":[{"href":"https:\/\/www.travel-insight.fr\/es\/wp-json\/wp\/v2\/media?parent=18700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.travel-insight.fr\/es\/wp-json\/wp\/v2\/categories?post=18700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.travel-insight.fr\/es\/wp-json\/wp\/v2\/tags?post=18700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}