{"id":19188,"date":"2020-04-15T15:06:52","date_gmt":"2020-04-15T13:06:52","guid":{"rendered":"https:\/\/www.travel-insight.fr\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\/"},"modified":"2020-04-15T15:06:52","modified_gmt":"2020-04-15T13:06:52","slug":"intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa","status":"publish","type":"post","link":"https:\/\/www.travel-insight.fr\/it\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\/","title":{"rendered":"Intervista ai clienti: Il lancio dell&#8217;agenzia di viaggi Evasions USA"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\"><a href=\"https:\/\/www.travel-insight.fr\/lancer-son-agence-de-voyage-digital\/\">Quando hai lanciato la tua agenzia di viaggi<\/a> specializzata negli Stati Uniti, hai deciso di affidarti a noi e oggi la tua reputazione \u00e8 ben consolidata.<br \/>\nDalla creazione della tua identit\u00e0, al tuo sito web, al tuo lancio sui social network, siamo stati coinvolti in un&#8217;ampia gamma di progetti per garantirti un appeal efficace.<br \/>\nEcco una panoramica di questa collaborazione.    <\/span><\/p>\n<hr>\n<p style=\"text-align: justify;\"><b>Puoi presentarti e parlarci di Evasions USA?<\/b><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\"><a href=\"https:\/\/www.evasionsusa.com\/\"><a href=\"https:\/\/www.evasionsusa.com\/\">Evasions USA \u00e8 un&#8217;agenzia di viaggi \/ tour operator specializzata negli Stati Uniti.<\/a><\/a><a href=\"https:\/\/www.evasionsusa.com\/\"><img decoding=\"async\" class=\"alignleft wp-image-2842 size-thumbnail\" src=\"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/04\/EvasionsUSA_WebHD-150x150.png\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/04\/EvasionsUSA_WebHD-150x150.png 150w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/04\/EvasionsUSA_WebHD-300x300.png 300w, https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/04\/EvasionsUSA_WebHD.png 360w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>.<br \/>\nLes voyageurs font appel \u00e0 nos services pour l\u2019organisation de leurs voyages sur mesure aux USA (vols, h\u00e9bergements, location de voiture, camping-car, moto, activit\u00e9s\u2026).<br \/>\nNotre id\u00e9e premi\u00e8re est de cr\u00e9er des voyages adapt\u00e9s \u00e0 tout budget.<br \/>\nEn effet, chez Evasions USA, nous proposons aussi bien des motels, des logements atypiques, des h\u00f4tels de cha\u00eenes ou encore des h\u00e9bergements 4 et 5 \u00e9toiles, afin de r\u00e9pondre \u00e0 tous les souhaits de nos clients.   <\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><b>Quali sono le sfide attuali per un&#8217;agenzia di viaggi come la tua in termini di comunicazione digitale?<\/b><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u00c8 fondamentale creare un&#8217;immagine forte sui social network, soprattutto per un&#8217;agenzia come la nostra che \u00e8 al 100% online.<br \/>\nDobbiamo distinguerci dalla massa offrendo contenuti diversi e pi\u00f9 autentici e aggiungendo la nostra conoscenza del Paese attraverso i vari mezzi di comunicazione scelti per la nostra agenzia.<br \/>\nAttualmente stiamo lavorando per sviluppare i nostri media esistenti e creare un nuovo mezzo di condivisione con la nostra comunit\u00e0 di viaggiatori.<br \/>\nLa nostra sfida: diventare un punto di riferimento per i <a href=\"https:\/\/www.evasionsusa.com\/contactez-nous\/\">viaggi su misura negli Stati Uniti<\/a>!   <\/span><\/p>\n<p><div class=\"video-container\"><iframe style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2FEvasionsUsa%2Fposts%2F725096124632222&amp;width=500\" width=\"500\" height=\"752\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/div><\/p>\n<p style=\"text-align: justify;\"><b>Perch\u00e9 e come sei arrivato a lavorare con la nostra agenzia di comunicazione?  <\/b><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Il nostro punto di partenza era che se volevamo svilupparci rapidamente e professionalmente, dovevamo circondarci di un buon team di comunicazione in grado di supportarci, stabilire una strategia e realizzare le nostre idee.<br \/>\nCi siamo rivolti a Travel Insight per attingere alla loro esperienza nella <a href=\"https:\/\/www.travel-insight.fr\/\">comunicazione dei viaggi e del turismo<\/a>.<br \/>\nDopo aver incontrato C\u00e9lia e Stanislas a Parigi, l&#8217;avventura \u00e8 iniziata!  <\/span><\/p>\n<p style=\"text-align: justify;\"><b>Cosa hai imparato dalla nostra collaborazione e quali sono stati i tuoi successi?  <\/b><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La nostra collaborazione ci ha permesso di creare e far crescere la nostra community sui social network, con oltre 10.000 follower su Facebook e diverse migliaia su Instagram.<br \/>\nL&#8217;interazione con la nostra fedele comunit\u00e0 di appassionati di viaggi e di Stati Uniti \u00e8 il nostro pi\u00f9 grande motivo di orgoglio, perch\u00e9 ora comprende un gran numero di clienti che si sono affidati a noi per creare i loro viaggi. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Siamo anche riusciti a entrare in contatto con diversi influencer, in particolare con <a href=\"http:\/\/www.youmakefashion.fr\/\">Margot del blog YouMakeFashion<\/a>, con cui abbiamo lavorato per la prima volta.<br \/>\nSiamo riusciti a realizzare un progetto comune per la sua comunit\u00e0 e per Evasions USA.<br \/>\nLa collaborazione \u00e8 stata un vero successo e siamo ancora in contatto per lavorare a un futuro viaggio insieme.  <\/span><\/p>\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\" data-instgrm-captioned=\"\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/Borxy5bARHM\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"12\">\n<div style=\"padding: 16px;\">\n<p>&nbsp;<\/p>\n<div style=\"display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display: block; height: 50px; margin: 0 auto 12px; width: 50px;\"><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\"color: #3897f0; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: 550; line-height: 18px;\">Guarda questo post su Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #f4f4f4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg);\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\"width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\"background-color: #f4f4f4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"margin: 8px 0 0 0; padding: 0 4px;\"><a style=\"color: #000; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none; word-wrap: break-word;\" href=\"https:\/\/www.instagram.com\/p\/Borxy5bARHM\/?utm_source=ig_embed&amp;utm_campaign=loading\" target=\"_blank\" rel=\"noopener noreferrer\">Il nostro programma @evasionsusa sta crescendo\ud83d\ude48 Ieri siamo stati a Moab in Hummer con @moabadventurecenter e oggi di nuovo, ma nelle canyonlands @discovermoab \ud83d\ude4c\ud83c\udffb\ud83c\uddfa\ud83c\uddf8 #cestlheuredelenveloppe<\/a><\/p>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\">Una pubblicazione condivisa da <a style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px;\" href=\"https:\/\/www.instagram.com\/youmakefashion\/?utm_source=ig_embed&amp;utm_campaign=loading\" target=\"_blank\" rel=\"noopener noreferrer\"> Margot YMF<\/a> (@youmakefashion) su  <time style=\"font-family: Arial,sans-serif; font-size: 14px; line-height: 17px;\" datetime=\"2018-10-08T19:34:28+00:00\">8 ott.<br \/>\n2018 alle 12:34 PDT <\/time><\/p>\n<\/div>\n<\/blockquote>\n<p><script async=\"\" src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Pensiamo con molto affetto anche a <a href=\"http:\/\/ellesenparlent.com\/\">Coralie del blog Ellesenparlent<\/a>, che ha scoperto la California in coppia; In\u00e8s (@inesduhard) e Pauline del blog <a href=\"https:\/\/blondie-baby.com\/\">Blondie-Baby<\/a>, che hanno viaggiato per il New England con le loro amiche ad Halloween; e Marion del blog <a href=\"https:\/\/www.instagram.com\/fringeandfrange\/?hl=fr\">Fringe&amp;Frange<\/a>, che ha viaggiato per la Louisiana lo scorso novembre con la sua bellissima famiglia!<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Un grande ringraziamento a Travel Insight per la scelta di influencer attenti e autentici, fondamentale per il successo delle nostre collaborazioni!<\/span><\/p>\n<p style=\"text-align: justify;\"><b>Come sono stati misurati i risultati di queste operazioni?  <\/b><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Semplicemente a causa dell&#8217;aumento delle richieste di preventivo.<\/span><\/p>\n<p style=\"text-align: justify;\"><b>Cosa ne hai ricavato?<\/b><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Questo ci ha permesso di rafforzare la nostra immagine, di sviluppare la nostra comunit\u00e0 e la nostra base di clienti e, soprattutto, di far conoscere i nostri servizi a un gran numero di persone.<\/span><\/p>\n<p style=\"text-align: justify;\"><b>Quali sono i tuoi progetti futuri?  <\/b><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Inizialmente, vogliamo continuare il nostro sviluppo ampliando il nostro team per rispondere in modo rapido e qualitativo alla crescente domanda.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Vogliamo creare un nuovo mezzo di comunicazione per consentire alla nostra comunit\u00e0 di saperne di pi\u00f9 sugli Stati Uniti.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Stiamo creando degli strumenti sui nostri <a href=\"https:\/\/www.travel-insight.fr\/nos-services\/strategie-digitale\/\">social network per mettere i nostri passeggeri al centro della nostra comunicazione<\/a>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Infine, svilupperemo nuove partnership per aiutare i nostri viaggiatori a scoprire il maggior numero possibile di regioni e fargli venire ancora pi\u00f9 voglia di viaggiare in questo magnifico paese.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando hai lanciato la tua agenzia di viaggi specializzata negli Stati Uniti, hai deciso di affidarti a noi e oggi la tua reputazione \u00e8 ben consolidata. Dalla creazione della tua identit\u00e0, al tuo sito web, al tuo lancio sui social network, siamo stati coinvolti in un&#8217;ampia gamma di progetti per garantirti un appeal efficace. Ecco&hellip; <a class=\"more-link\" href=\"https:\/\/www.travel-insight.fr\/it\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\/\">Continue reading <span class=\"screen-reader-text\">Intervista ai clienti: Il lancio dell&#8217;agenzia di viaggi Evasions USA<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":12130,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[652,579,723],"tags":[],"class_list":["post-19188","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-i-social-network","category-relazioni-con-gli-influencer","category-testimonianze","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Intervista ai clienti: Il lancio dell&#039;agenzia di viaggi Evasions USA &#8211; Travel Insight<\/title>\n<meta name=\"description\" content=\"Leggi la testimonianza di EvaionsUSA, un&#039;agenzia di viaggi specializzata negli Stati Uniti!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.travel-insight.fr\/it\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Intervista ai clienti: Il lancio dell&#039;agenzia di viaggi Evasions USA &#8211; Travel Insight\" \/>\n<meta property=\"og:description\" content=\"Leggi la testimonianza di EvaionsUSA, un&#039;agenzia di viaggi specializzata negli Stati Uniti!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.travel-insight.fr\/it\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\/\" \/>\n<meta property=\"og:site_name\" content=\"Travel Insight\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/fr-fr.facebook.com\/travelinsightfr\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-15T13:06:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/04\/evasions-usa-communication-agence-voyage-reseaux-sociaux.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1185\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Stanislas Lucien\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/lustanislas?lang=fr\" \/>\n<meta name=\"twitter:site\" content=\"@travelinsightfr\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Stanislas Lucien\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/it\\\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/it\\\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\\\/\"},\"author\":{\"name\":\"Stanislas Lucien\",\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/it\\\/#\\\/schema\\\/person\\\/2eb584d7c26497ac1a033e25615bb12b\"},\"headline\":\"Intervista ai clienti: Il lancio dell&#8217;agenzia di viaggi Evasions USA\",\"datePublished\":\"2020-04-15T13:06:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/it\\\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\\\/\"},\"wordCount\":756,\"publisher\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/it\\\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.travel-insight.fr\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/evasions-usa-communication-agence-voyage-reseaux-sociaux.jpg\",\"articleSection\":[\"I social network\",\"Relazioni con gli influencer\",\"Testimonianze\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/it\\\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\\\/\",\"url\":\"https:\\\/\\\/www.travel-insight.fr\\\/it\\\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\\\/\",\"name\":\"Intervista ai clienti: Il lancio dell'agenzia di viaggi Evasions USA &#8211; Travel Insight\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/it\\\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/it\\\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.travel-insight.fr\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/evasions-usa-communication-agence-voyage-reseaux-sociaux.jpg\",\"datePublished\":\"2020-04-15T13:06:52+00:00\",\"description\":\"Leggi la testimonianza di EvaionsUSA, un'agenzia di viaggi specializzata negli Stati Uniti!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/it\\\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.travel-insight.fr\\\/it\\\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/it\\\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.travel-insight.fr\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/evasions-usa-communication-agence-voyage-reseaux-sociaux.jpg\",\"contentUrl\":\"https:\\\/\\\/www.travel-insight.fr\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/evasions-usa-communication-agence-voyage-reseaux-sociaux.jpg\",\"width\":1185,\"height\":854},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/it\\\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.travel-insight.fr\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Intervista ai clienti: Il lancio dell&rsquo;agenzia di viaggi Evasions USA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.travel-insight.fr\\\/it\\\/\",\"name\":\"Travel-Insight\",\"description\":\"Agence de communication tourisme\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.travel-insight.fr\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/it\\\/#organization\",\"name\":\"Travel-Insight\",\"url\":\"https:\\\/\\\/www.travel-insight.fr\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.travel-insight.fr\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/logo-travel-insight-identit\u00e9-visuelle-agence-influence.jpg\",\"contentUrl\":\"https:\\\/\\\/www.travel-insight.fr\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/logo-travel-insight-identit\u00e9-visuelle-agence-influence.jpg\",\"width\":800,\"height\":800,\"caption\":\"Travel-Insight\"},\"image\":{\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/fr-fr.facebook.com\\\/travelinsightfr\\\/\",\"https:\\\/\\\/x.com\\\/travelinsightfr\",\"https:\\\/\\\/www.instagram.com\\\/travelinsightfr\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/travel-insight-strat\u00e9gie-digitale-&amp;-e-influence-du-tourisme.\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.travel-insight.fr\\\/it\\\/#\\\/schema\\\/person\\\/2eb584d7c26497ac1a033e25615bb12b\",\"name\":\"Stanislas Lucien\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c991db95e2f3a51755573d538e908a82c805ab5e872d0c3c348868e5e518a5f1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c991db95e2f3a51755573d538e908a82c805ab5e872d0c3c348868e5e518a5f1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c991db95e2f3a51755573d538e908a82c805ab5e872d0c3c348868e5e518a5f1?s=96&d=mm&r=g\",\"caption\":\"Stanislas Lucien\"},\"description\":\"C\u2019est un geek, il cr\u00e9e des sites et optimise le SEO pour \u00ab s\u2019amuser \u00bb le week-end pendant qu\u2019on regarde les s\u00e9ries recommand\u00e9es par Jeanne. Mais ce passionn\u00e9 de techno et du web sait aussi communiquer et trouver le meilleur moyen pour g\u00e9n\u00e9rer du trafic ! L\u2019administratif, c\u2019est son quotidien, la communication digitale, une vocation. Il nous envoie d\u2019ailleurs un gif chaque jour, sur sa deuxi\u00e8me passion : la bonne table.\",\"sameAs\":[\"https:\\\/\\\/www.travel-insight.fr\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/stanislaslucien\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/lustanislas?lang=fr\"],\"url\":\"https:\\\/\\\/www.travel-insight.fr\\\/it\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Intervista ai clienti: Il lancio dell'agenzia di viaggi Evasions USA &#8211; Travel Insight","description":"Leggi la testimonianza di EvaionsUSA, un'agenzia di viaggi specializzata negli Stati Uniti!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.travel-insight.fr\/it\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\/","og_locale":"it_IT","og_type":"article","og_title":"Intervista ai clienti: Il lancio dell'agenzia di viaggi Evasions USA &#8211; Travel Insight","og_description":"Leggi la testimonianza di EvaionsUSA, un'agenzia di viaggi specializzata negli Stati Uniti!","og_url":"https:\/\/www.travel-insight.fr\/it\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\/","og_site_name":"Travel Insight","article_publisher":"https:\/\/fr-fr.facebook.com\/travelinsightfr\/","article_published_time":"2020-04-15T13:06:52+00:00","og_image":[{"width":1185,"height":854,"url":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/04\/evasions-usa-communication-agence-voyage-reseaux-sociaux.jpg","type":"image\/jpeg"}],"author":"Stanislas Lucien","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/lustanislas?lang=fr","twitter_site":"@travelinsightfr","twitter_misc":{"Scritto da":"Stanislas Lucien","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.travel-insight.fr\/it\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\/#article","isPartOf":{"@id":"https:\/\/www.travel-insight.fr\/it\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\/"},"author":{"name":"Stanislas Lucien","@id":"https:\/\/www.travel-insight.fr\/it\/#\/schema\/person\/2eb584d7c26497ac1a033e25615bb12b"},"headline":"Intervista ai clienti: Il lancio dell&#8217;agenzia di viaggi Evasions USA","datePublished":"2020-04-15T13:06:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.travel-insight.fr\/it\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\/"},"wordCount":756,"publisher":{"@id":"https:\/\/www.travel-insight.fr\/it\/#organization"},"image":{"@id":"https:\/\/www.travel-insight.fr\/it\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/04\/evasions-usa-communication-agence-voyage-reseaux-sociaux.jpg","articleSection":["I social network","Relazioni con gli influencer","Testimonianze"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.travel-insight.fr\/it\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\/","url":"https:\/\/www.travel-insight.fr\/it\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\/","name":"Intervista ai clienti: Il lancio dell'agenzia di viaggi Evasions USA &#8211; Travel Insight","isPartOf":{"@id":"https:\/\/www.travel-insight.fr\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.travel-insight.fr\/it\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\/#primaryimage"},"image":{"@id":"https:\/\/www.travel-insight.fr\/it\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/04\/evasions-usa-communication-agence-voyage-reseaux-sociaux.jpg","datePublished":"2020-04-15T13:06:52+00:00","description":"Leggi la testimonianza di EvaionsUSA, un'agenzia di viaggi specializzata negli Stati Uniti!","breadcrumb":{"@id":"https:\/\/www.travel-insight.fr\/it\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.travel-insight.fr\/it\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.travel-insight.fr\/it\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\/#primaryimage","url":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/04\/evasions-usa-communication-agence-voyage-reseaux-sociaux.jpg","contentUrl":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/04\/evasions-usa-communication-agence-voyage-reseaux-sociaux.jpg","width":1185,"height":854},{"@type":"BreadcrumbList","@id":"https:\/\/www.travel-insight.fr\/it\/intervista-ai-clienti-il-lancio-dellagenzia-di-viaggi-evasions-usa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.travel-insight.fr\/it\/"},{"@type":"ListItem","position":2,"name":"Intervista ai clienti: Il lancio dell&rsquo;agenzia di viaggi Evasions USA"}]},{"@type":"WebSite","@id":"https:\/\/www.travel-insight.fr\/it\/#website","url":"https:\/\/www.travel-insight.fr\/it\/","name":"Travel-Insight","description":"Agence de communication tourisme","publisher":{"@id":"https:\/\/www.travel-insight.fr\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.travel-insight.fr\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.travel-insight.fr\/it\/#organization","name":"Travel-Insight","url":"https:\/\/www.travel-insight.fr\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.travel-insight.fr\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/06\/logo-travel-insight-identit\u00e9-visuelle-agence-influence.jpg","contentUrl":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/06\/logo-travel-insight-identit\u00e9-visuelle-agence-influence.jpg","width":800,"height":800,"caption":"Travel-Insight"},"image":{"@id":"https:\/\/www.travel-insight.fr\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/fr-fr.facebook.com\/travelinsightfr\/","https:\/\/x.com\/travelinsightfr","https:\/\/www.instagram.com\/travelinsightfr\/","https:\/\/www.linkedin.com\/company\/travel-insight-strat\u00e9gie-digitale-&amp;-e-influence-du-tourisme."]},{"@type":"Person","@id":"https:\/\/www.travel-insight.fr\/it\/#\/schema\/person\/2eb584d7c26497ac1a033e25615bb12b","name":"Stanislas Lucien","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c991db95e2f3a51755573d538e908a82c805ab5e872d0c3c348868e5e518a5f1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c991db95e2f3a51755573d538e908a82c805ab5e872d0c3c348868e5e518a5f1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c991db95e2f3a51755573d538e908a82c805ab5e872d0c3c348868e5e518a5f1?s=96&d=mm&r=g","caption":"Stanislas Lucien"},"description":"C\u2019est un geek, il cr\u00e9e des sites et optimise le SEO pour \u00ab s\u2019amuser \u00bb le week-end pendant qu\u2019on regarde les s\u00e9ries recommand\u00e9es par Jeanne. Mais ce passionn\u00e9 de techno et du web sait aussi communiquer et trouver le meilleur moyen pour g\u00e9n\u00e9rer du trafic ! L\u2019administratif, c\u2019est son quotidien, la communication digitale, une vocation. Il nous envoie d\u2019ailleurs un gif chaque jour, sur sa deuxi\u00e8me passion : la bonne table.","sameAs":["https:\/\/www.travel-insight.fr\/","https:\/\/www.linkedin.com\/in\/stanislaslucien\/","https:\/\/x.com\/https:\/\/twitter.com\/lustanislas?lang=fr"],"url":"https:\/\/www.travel-insight.fr\/it\/author\/admin\/"}]}},"featured_image_src":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/04\/evasions-usa-communication-agence-voyage-reseaux-sociaux-600x400.jpg","featured_image_src_square":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/04\/evasions-usa-communication-agence-voyage-reseaux-sociaux-600x600.jpg","author_info":{"display_name":"Stanislas Lucien","author_link":"https:\/\/www.travel-insight.fr\/it\/author\/admin\/"},"jetpack_featured_media_url":"https:\/\/www.travel-insight.fr\/wp-content\/uploads\/2020\/04\/evasions-usa-communication-agence-voyage-reseaux-sociaux.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.travel-insight.fr\/it\/wp-json\/wp\/v2\/posts\/19188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.travel-insight.fr\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.travel-insight.fr\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.travel-insight.fr\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.travel-insight.fr\/it\/wp-json\/wp\/v2\/comments?post=19188"}],"version-history":[{"count":0,"href":"https:\/\/www.travel-insight.fr\/it\/wp-json\/wp\/v2\/posts\/19188\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.travel-insight.fr\/it\/wp-json\/wp\/v2\/media\/12130"}],"wp:attachment":[{"href":"https:\/\/www.travel-insight.fr\/it\/wp-json\/wp\/v2\/media?parent=19188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.travel-insight.fr\/it\/wp-json\/wp\/v2\/categories?post=19188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.travel-insight.fr\/it\/wp-json\/wp\/v2\/tags?post=19188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}